{"id":8250,"date":"2026-01-14T02:33:56","date_gmt":"2026-01-14T00:33:56","guid":{"rendered":"https:\/\/autocity.dev.webeng.co\/nissan-site\/used-car\/nissan-1-0-visia-9\/"},"modified":"2026-05-13T09:12:13","modified_gmt":"2026-05-13T07:12:13","slug":"nissan-1-0-visia-9","status":"publish","type":"used-car","link":"https:\/\/autocity.dev.webeng.co\/nissan-site\/used-car\/nissan-1-0-visia-9\/","title":{"rendered":"Nissan 1.0 Visia"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"make":[39,25],"condition":[56],"bodytype":[8],"dealer":[5],"class_list":["post-8250","used-car","type-used-car","status-publish","hentry","make-magnite","make-nissan","bodytype-suv","dealer-nissan-nigel"],"acf":[],"_links":{"self":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/used-cars\/8250","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/used-cars"}],"about":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/types\/used-car"}],"wp:attachment":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/media?parent=8250"}],"wp:term":[{"taxonomy":"make","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/make?post=8250"},{"taxonomy":"condition","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/condition?post=8250"},{"taxonomy":"bodytype","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/bodytype?post=8250"},{"taxonomy":"dealer","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/dealer?post=8250"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}