{"id":8235,"date":"2026-01-14T02:33:41","date_gmt":"2026-01-14T00:33:41","guid":{"rendered":"https:\/\/autocity.dev.webeng.co\/nissan-site\/used-car\/nissan-navara-2-5ddti-pro-4x-4x4-a-t-d-c-p-u\/"},"modified":"2026-05-13T09:12:09","modified_gmt":"2026-05-13T07:12:09","slug":"nissan-navara-2-5ddti-pro-4x-4x4-a-t-d-c-p-u","status":"publish","type":"used-car","link":"https:\/\/autocity.dev.webeng.co\/nissan-site\/used-car\/nissan-navara-2-5ddti-pro-4x-4x4-a-t-d-c-p-u\/","title":{"rendered":"Nissan NAVARA 2.5DDTi PRO-4X 4X4 A\/T D\/C P\/U"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"make":[27,25],"condition":[22],"bodytype":[15],"dealer":[5],"class_list":["post-8235","used-car","type-used-car","status-publish","hentry","make-navara","make-nissan","bodytype-double-cab","dealer-nissan-nigel"],"acf":[],"_links":{"self":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/used-cars\/8235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/used-cars"}],"about":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/types\/used-car"}],"wp:attachment":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/media?parent=8235"}],"wp:term":[{"taxonomy":"make","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/make?post=8235"},{"taxonomy":"condition","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/condition?post=8235"},{"taxonomy":"bodytype","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/bodytype?post=8235"},{"taxonomy":"dealer","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/dealer?post=8235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}