{"id":8219,"date":"2026-01-14T02:33:23","date_gmt":"2026-01-14T00:33:23","guid":{"rendered":"https:\/\/autocity.dev.webeng.co\/nissan-site\/used-car\/volkswagen-polo-vivo-gp-1-4-conceptline-5dr\/"},"modified":"2026-05-13T09:12:05","modified_gmt":"2026-05-13T07:12:05","slug":"volkswagen-polo-vivo-gp-1-4-conceptline-5dr","status":"publish","type":"used-car","link":"https:\/\/autocity.dev.webeng.co\/nissan-site\/used-car\/volkswagen-polo-vivo-gp-1-4-conceptline-5dr\/","title":{"rendered":"Volkswagen POLO VIVO GP 1.4 CONCEPTLINE 5DR"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"make":[42,41],"condition":[22],"bodytype":[21],"dealer":[5],"class_list":["post-8219","used-car","type-used-car","status-publish","hentry","make-polo","make-volkswagen","bodytype-hatch","dealer-nissan-nigel"],"acf":[],"_links":{"self":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/used-cars\/8219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/used-cars"}],"about":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/types\/used-car"}],"wp:attachment":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/media?parent=8219"}],"wp:term":[{"taxonomy":"make","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/make?post=8219"},{"taxonomy":"condition","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/condition?post=8219"},{"taxonomy":"bodytype","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/bodytype?post=8219"},{"taxonomy":"dealer","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/dealer?post=8219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}