{"id":8216,"date":"2026-01-14T02:32:26","date_gmt":"2026-01-14T00:32:26","guid":{"rendered":"https:\/\/autocity.dev.webeng.co\/nissan-site\/used-car\/ford-everest-2-0d-xlt-sport-a-t\/"},"modified":"2026-05-13T09:11:55","modified_gmt":"2026-05-13T07:11:55","slug":"ford-everest-2-0d-xlt-sport-a-t","status":"publish","type":"used-car","link":"https:\/\/autocity.dev.webeng.co\/nissan-site\/used-car\/ford-everest-2-0d-xlt-sport-a-t\/","title":{"rendered":"FORD EVEREST 2.0D XLT SPORT A\/T"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"make":[136,30],"condition":[22],"bodytype":[8],"dealer":[3],"class_list":["post-8216","used-car","type-used-car","status-publish","hentry","make-everest","make-ford","bodytype-suv","dealer-nissan-heidelberg"],"acf":[],"_links":{"self":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/used-cars\/8216","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/used-cars"}],"about":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/types\/used-car"}],"wp:attachment":[{"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/media?parent=8216"}],"wp:term":[{"taxonomy":"make","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/make?post=8216"},{"taxonomy":"condition","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/condition?post=8216"},{"taxonomy":"bodytype","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/bodytype?post=8216"},{"taxonomy":"dealer","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/nissan-site\/wp-json\/wp\/v2\/dealer?post=8216"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}