{"id":1510,"date":"2026-01-14T02:33:58","date_gmt":"2026-01-14T00:33:58","guid":{"rendered":"https:\/\/autocity.dev.webeng.co\/haval-site\/used-car\/ford-everest-2-0d-bi-turbo-ltd-4x4-a-t\/"},"modified":"2026-05-13T04:21:07","modified_gmt":"2026-05-13T02:21:07","slug":"ford-everest-2-0d-bi-turbo-ltd-4x4-a-t","status":"publish","type":"used-car","link":"https:\/\/autocity.dev.webeng.co\/haval-site\/used-car\/ford-everest-2-0d-bi-turbo-ltd-4x4-a-t\/","title":{"rendered":"FORD EVEREST 2.0D BI-TURBO LTD 4X4 A\/T"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"make":[80,43],"condition":[14],"bodytype":[7],"dealer":[3],"class_list":["post-1510","used-car","type-used-car","status-publish","hentry","make-everest","make-ford","bodytype-suv","dealer-autocity-gwm-haval-heidelberg"],"acf":[],"_links":{"self":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/used-cars\/1510","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/used-cars"}],"about":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/types\/used-car"}],"wp:attachment":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/media?parent=1510"}],"wp:term":[{"taxonomy":"make","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/make?post=1510"},{"taxonomy":"condition","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/condition?post=1510"},{"taxonomy":"bodytype","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/bodytype?post=1510"},{"taxonomy":"dealer","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/dealer?post=1510"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}