{"id":1452,"date":"2026-01-14T02:32:49","date_gmt":"2026-01-14T00:32:49","guid":{"rendered":"https:\/\/autocity.dev.webeng.co\/haval-site\/used-car\/renault-kiger-1-0t-zen\/"},"modified":"2026-05-12T07:02:22","modified_gmt":"2026-05-12T05:02:22","slug":"renault-kiger-1-0t-zen","status":"publish","type":"used-car","link":"https:\/\/autocity.dev.webeng.co\/haval-site\/used-car\/renault-kiger-1-0t-zen\/","title":{"rendered":"Renault KIGER 1.0T ZEN"},"content":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"make":[70,33],"condition":[14],"bodytype":[7],"dealer":[3],"class_list":["post-1452","used-car","type-used-car","status-publish","hentry","make-kiger","make-renault","bodytype-suv","dealer-autocity-gwm-haval-heidelberg"],"acf":[],"_links":{"self":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/used-cars\/1452","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/used-cars"}],"about":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/types\/used-car"}],"wp:attachment":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/media?parent=1452"}],"wp:term":[{"taxonomy":"make","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/make?post=1452"},{"taxonomy":"condition","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/condition?post=1452"},{"taxonomy":"bodytype","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/bodytype?post=1452"},{"taxonomy":"dealer","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/dealer?post=1452"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}