{"id":91,"date":"2023-04-27T14:09:44","date_gmt":"2023-04-27T12:09:44","guid":{"rendered":"https:\/\/autocity.dev.webeng.co\/haval-site\/special-offer\/haval-jolion-s"},"modified":"2023-11-21T12:20:05","modified_gmt":"2023-11-21T10:20:05","slug":"haval-jolion-s","status":"publish","type":"special-offer","link":"https:\/\/autocity.dev.webeng.co\/haval-site\/special-offer\/haval-jolion-s\/","title":{"rendered":"Haval JOLION S"},"content":{"rendered":"","protected":false},"author":5,"featured_media":0,"template":"","meta":{"_acf_changed":false},"model":[8],"class_list":["post-91","special-offer","type-special-offer","status-publish","hentry","model-jolion"],"acf":[],"_links":{"self":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/special-offer\/91","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/special-offer"}],"about":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/types\/special-offer"}],"author":[{"embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/users\/5"}],"wp:attachment":[{"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/media?parent=91"}],"wp:term":[{"taxonomy":"model","embeddable":true,"href":"https:\/\/autocity.dev.webeng.co\/haval-site\/wp-json\/wp\/v2\/model?post=91"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}